{"id":10453,"date":"2025-12-30T20:38:27","date_gmt":"2025-12-30T20:38:27","guid":{"rendered":"https:\/\/gravel-bikes.cc\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/"},"modified":"2025-12-30T20:38:27","modified_gmt":"2025-12-30T20:38:27","slug":"set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent","status":"publish","type":"product","link":"https:\/\/gravel-bikes.cc\/fr\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/","title":{"rendered":"SET D&rsquo;USURE Cassette SRAM XG-1275 GX Eagle Full Pin 10-50 dents noir + Cha\u00eene SRAM GX Eagle argent"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"pwb-brand":[],"product_brand":[],"product_cat":[756],"product_tag":[],"class_list":["post-10453","product","type-product","status-publish","product_cat-non-classe","first","instock","taxable","shipping-taxable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/gravel-bikes.cc\/fr\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"GRAVEL BIKES.cc - GRAVEL BIKES from Hamburg Germany\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"SET D\u2019USURE Cassette SRAM XG-1275 GX Eagle Full Pin 10-50 dents noir + Cha\u00eene SRAM GX Eagle argent - GRAVEL BIKES.cc\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/gravel-bikes.cc\/fr\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/gravel-bikes.cc\/wp-content\/uploads\/2026\/02\/426370018_742920761164595_709478854362802977_n.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/gravel-bikes.cc\/wp-content\/uploads\/2026\/02\/426370018_742920761164595_709478854362802977_n.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-12-30T20:38:27+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-12-30T20:38:27+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063771884607\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"SET D\u2019USURE Cassette SRAM XG-1275 GX Eagle Full Pin 10-50 dents noir + Cha\u00eene SRAM GX Eagle argent - GRAVEL BIKES.cc\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/gravel-bikes.cc\/wp-content\/uploads\/2026\/02\/426370018_742920761164595_709478854362802977_n.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/produkt\\\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/boutique\\\/#listItem\",\"name\":\"Boutique\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/boutique\\\/#listItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/boutique\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/produkt-kategorie\\\/non-classe\\\/#listItem\",\"name\":\"Non class\\u00e9\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/produkt-kategorie\\\/non-classe\\\/#listItem\",\"position\":3,\"name\":\"Non class\\u00e9\",\"item\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/produkt-kategorie\\\/non-classe\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/produkt\\\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\\\/#listItem\",\"name\":\"SET D&rsquo;USURE Cassette SRAM XG-1275 GX Eagle Full Pin 10-50 dents noir + Cha\\u00eene SRAM GX Eagle argent\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/boutique\\\/#listItem\",\"name\":\"Boutique\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/produkt\\\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\\\/#listItem\",\"position\":4,\"name\":\"SET D&rsquo;USURE Cassette SRAM XG-1275 GX Eagle Full Pin 10-50 dents noir + Cha\\u00eene SRAM GX Eagle argent\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/produkt-kategorie\\\/non-classe\\\/#listItem\",\"name\":\"Non class\\u00e9\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/produkt\\\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\\\/#itempage\",\"url\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/produkt\\\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\\\/\",\"name\":\"SET D\\u2019USURE Cassette SRAM XG-1275 GX Eagle Full Pin 10-50 dents noir + Cha\\u00eene SRAM GX Eagle argent - GRAVEL BIKES.cc\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/produkt\\\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\\\/#breadcrumblist\"},\"datePublished\":\"2025-12-30T20:38:27+00:00\",\"dateModified\":\"2025-12-30T20:38:27+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/#organization\",\"name\":\"GRAVEL BIKES.cc\",\"description\":\"GRAVEL BIKES from Hamburg Germany\",\"url\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/\",\"telephone\":\"+49174616928\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/gravel-bikes.cc\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/426370018_742920761164595_709478854362802977_n.jpg\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/produkt\\\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\\\/#organizationLogo\",\"width\":150,\"height\":150},\"image\":{\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/produkt\\\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063771884607\",\"https:\\\/\\\/www.instagram.com\\\/gravel_bikes.cc\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/\",\"name\":\"GRAVEL BIKES.cc\",\"description\":\"GRAVEL BIKES from Hamburg Germany\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/gravel-bikes.cc\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"SET D\u2019USURE Cassette SRAM XG-1275 GX Eagle Full Pin 10-50 dents noir + Cha\u00eene SRAM GX Eagle argent - GRAVEL BIKES.cc","description":"","canonical_url":"https:\/\/gravel-bikes.cc\/fr\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/gravel-bikes.cc\/fr\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/gravel-bikes.cc\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/gravel-bikes.cc\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/gravel-bikes.cc\/fr\/boutique\/#listItem","name":"Boutique"}},{"@type":"ListItem","@id":"https:\/\/gravel-bikes.cc\/fr\/boutique\/#listItem","position":2,"name":"Boutique","item":"https:\/\/gravel-bikes.cc\/fr\/boutique\/","nextItem":{"@type":"ListItem","@id":"https:\/\/gravel-bikes.cc\/fr\/produkt-kategorie\/non-classe\/#listItem","name":"Non class\u00e9"},"previousItem":{"@type":"ListItem","@id":"https:\/\/gravel-bikes.cc\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/gravel-bikes.cc\/fr\/produkt-kategorie\/non-classe\/#listItem","position":3,"name":"Non class\u00e9","item":"https:\/\/gravel-bikes.cc\/fr\/produkt-kategorie\/non-classe\/","nextItem":{"@type":"ListItem","@id":"https:\/\/gravel-bikes.cc\/fr\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/#listItem","name":"SET D&rsquo;USURE Cassette SRAM XG-1275 GX Eagle Full Pin 10-50 dents noir + Cha\u00eene SRAM GX Eagle argent"},"previousItem":{"@type":"ListItem","@id":"https:\/\/gravel-bikes.cc\/fr\/boutique\/#listItem","name":"Boutique"}},{"@type":"ListItem","@id":"https:\/\/gravel-bikes.cc\/fr\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/#listItem","position":4,"name":"SET D&rsquo;USURE Cassette SRAM XG-1275 GX Eagle Full Pin 10-50 dents noir + Cha\u00eene SRAM GX Eagle argent","previousItem":{"@type":"ListItem","@id":"https:\/\/gravel-bikes.cc\/fr\/produkt-kategorie\/non-classe\/#listItem","name":"Non class\u00e9"}}]},{"@type":"ItemPage","@id":"https:\/\/gravel-bikes.cc\/fr\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/#itempage","url":"https:\/\/gravel-bikes.cc\/fr\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/","name":"SET D\u2019USURE Cassette SRAM XG-1275 GX Eagle Full Pin 10-50 dents noir + Cha\u00eene SRAM GX Eagle argent - GRAVEL BIKES.cc","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/gravel-bikes.cc\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/gravel-bikes.cc\/fr\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/#breadcrumblist"},"datePublished":"2025-12-30T20:38:27+00:00","dateModified":"2025-12-30T20:38:27+00:00"},{"@type":"Organization","@id":"https:\/\/gravel-bikes.cc\/fr\/#organization","name":"GRAVEL BIKES.cc","description":"GRAVEL BIKES from Hamburg Germany","url":"https:\/\/gravel-bikes.cc\/fr\/","telephone":"+49174616928","logo":{"@type":"ImageObject","url":"https:\/\/gravel-bikes.cc\/wp-content\/uploads\/2026\/02\/426370018_742920761164595_709478854362802977_n.jpg","@id":"https:\/\/gravel-bikes.cc\/fr\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/#organizationLogo","width":150,"height":150},"image":{"@id":"https:\/\/gravel-bikes.cc\/fr\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063771884607","https:\/\/www.instagram.com\/gravel_bikes.cc\/"]},{"@type":"WebSite","@id":"https:\/\/gravel-bikes.cc\/fr\/#website","url":"https:\/\/gravel-bikes.cc\/fr\/","name":"GRAVEL BIKES.cc","description":"GRAVEL BIKES from Hamburg Germany","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/gravel-bikes.cc\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"GRAVEL BIKES.cc - GRAVEL BIKES from Hamburg Germany","og:type":"article","og:title":"SET D\u2019USURE Cassette SRAM XG-1275 GX Eagle Full Pin 10-50 dents noir + Cha\u00eene SRAM GX Eagle argent - GRAVEL BIKES.cc","og:url":"https:\/\/gravel-bikes.cc\/fr\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/","og:image":"https:\/\/gravel-bikes.cc\/wp-content\/uploads\/2026\/02\/426370018_742920761164595_709478854362802977_n.jpg","og:image:secure_url":"https:\/\/gravel-bikes.cc\/wp-content\/uploads\/2026\/02\/426370018_742920761164595_709478854362802977_n.jpg","og:image:width":150,"og:image:height":150,"article:published_time":"2025-12-30T20:38:27+00:00","article:modified_time":"2025-12-30T20:38:27+00:00","article:publisher":"https:\/\/www.facebook.com\/profile.php?id=100063771884607","twitter:card":"summary_large_image","twitter:title":"SET D\u2019USURE Cassette SRAM XG-1275 GX Eagle Full Pin 10-50 dents noir + Cha\u00eene SRAM GX Eagle argent - GRAVEL BIKES.cc","twitter:image":"https:\/\/gravel-bikes.cc\/wp-content\/uploads\/2026\/02\/426370018_742920761164595_709478854362802977_n.jpg"},"aioseo_meta_data":{"post_id":"10453","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-03-22 14:02:32","updated":"2026-03-22 14:02:32","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gravel-bikes.cc\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gravel-bikes.cc\/fr\/boutique\/\" title=\"Boutique\">Boutique<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gravel-bikes.cc\/fr\/produkt-kategorie\/non-classe\/\" title=\"Non class\u00e9\">Non class\u00e9<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSET D\u2019USURE Cassette SRAM XG-1275 GX Eagle Full Pin 10-50 dents noir + Cha\u00eene SRAM GX Eagle argent\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/gravel-bikes.cc\/fr\/"},{"label":"Boutique","link":"https:\/\/gravel-bikes.cc\/fr\/boutique\/"},{"label":"Non class\u00e9","link":"https:\/\/gravel-bikes.cc\/fr\/produkt-kategorie\/non-classe\/"},{"label":"SET D&rsquo;USURE Cassette SRAM XG-1275 GX Eagle Full Pin 10-50 dents noir + Cha\u00eene SRAM GX Eagle argent","link":"https:\/\/gravel-bikes.cc\/fr\/produkt\/set-dusure-cassette-sram-xg-1275-gx-eagle-full-pin-10-50-dents-noir-chaine-sram-gx-eagle-argent\/"}],"df_price":"","df_sale_price":"","df_regular_price":"","df_image_link":"https:\/\/gravel-bikes.cc\/wp-content\/uploads\/woocommerce-placeholder-300x300.webp","brands":[],"_links":{"self":[{"href":"https:\/\/gravel-bikes.cc\/fr\/wp-json\/wp\/v2\/product\/10453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gravel-bikes.cc\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gravel-bikes.cc\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/gravel-bikes.cc\/fr\/wp-json\/wp\/v2\/media?parent=10453"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/gravel-bikes.cc\/fr\/wp-json\/wp\/v2\/pwb-brand?post=10453"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gravel-bikes.cc\/fr\/wp-json\/wp\/v2\/product_brand?post=10453"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gravel-bikes.cc\/fr\/wp-json\/wp\/v2\/product_cat?post=10453"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gravel-bikes.cc\/fr\/wp-json\/wp\/v2\/product_tag?post=10453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}